{"id":10329,"date":"2025-04-14T11:31:28","date_gmt":"2025-04-14T03:31:28","guid":{"rendered":"https:\/\/www.newcreationtv.org\/fr\/?post_type=sermon&#038;p=10329"},"modified":"2026-08-28T05:02:20","modified_gmt":"2026-08-28T03:02:20","slug":"pourquoi-jesus-est-la-reponse","status":"publish","type":"sermon","link":"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/","title":{"rendered":"Pourquoi J\u00e9sus est la r\u00e9ponse"},"content":{"rendered":"<p>\u00c0 l&#8217;homme aveugle de naissance, J\u00e9sus, la lumi\u00e8re du monde, a apport\u00e9 la vue. \u00c0 une foule affam\u00e9e de plus de 5 000 personnes, J\u00e9sus, le pain de vie, a fourni plus de nourriture qu&#8217;elles ne pouvaient en manger. Pour Marthe dont le fr\u00e8re, Lazare, \u00e9tait mort, J\u00e9sus s&#8217;est r\u00e9v\u00e9l\u00e9 comme la r\u00e9surrection et la vie. Dans ce message de foi, Joseph Prince vous montre pourquoi J\u00e9sus lui-m\u00eame &#8211; et non pas des m\u00e9thodes ou des principes &#8211; est la r\u00e9ponse \u00e0 tous les d\u00e9fis que vous rencontrez dans la vie. Voyez comment Sa gr\u00e2ce vous apporte provision, protection, sant\u00e9, paix et victoire d\u00e8s lors que vous obtenez une r\u00e9v\u00e9lation personnelle de qui Il est et de Sa bont\u00e9 dans le domaine o\u00f9 vous en avez besoin !<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_links_to":"","_links_to_target":""},"categories":[40,24,23],"tags":[465,467],"class_list":["post-10329","sermon","type-sermon","status-publish","hentry","category-la-faveur-de-dieu","category-pour-les-saisons-difficiles","category-qui-vous-etes-en-christ","tag-faveur-de-dieu","tag-justice"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pourquoi J\u00e9sus est la r\u00e9ponse | New Creation TV Fran\u00e7ais<\/title>\n<meta name=\"description\" content=\"\u00c0 l&#039;homme aveugle de naissance, J\u00e9sus, la lumi\u00e8re du monde, a apport\u00e9 la vue. \u00c0 une foule affam\u00e9e de plus de 5 000 personnes, J\u00e9sus, le pain de vie, a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pourquoi J\u00e9sus est la r\u00e9ponse | New Creation TV Fran\u00e7ais\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l&#039;homme aveugle de naissance, J\u00e9sus, la lumi\u00e8re du monde, a apport\u00e9 la vue. \u00c0 une foule affam\u00e9e de plus de 5 000 personnes, J\u00e9sus, le pain de vie, a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/\" \/>\n<meta property=\"og:site_name\" content=\"New Creation TV Fran\u00e7ais\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T03:02:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/\",\"url\":\"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/\",\"name\":\"Pourquoi J\u00e9sus est la r\u00e9ponse | New Creation TV Fran\u00e7ais\",\"isPartOf\":{\"@id\":\"https:\/\/www.newcreationtv.org\/fr\/#website\"},\"datePublished\":\"2025-04-14T03:31:28+00:00\",\"dateModified\":\"2026-08-28T03:02:20+00:00\",\"description\":\"\u00c0 l'homme aveugle de naissance, J\u00e9sus, la lumi\u00e8re du monde, a apport\u00e9 la vue. \u00c0 une foule affam\u00e9e de plus de 5 000 personnes, J\u00e9sus, le pain de vie, a\",\"breadcrumb\":{\"@id\":\"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.newcreationtv.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pourquoi J\u00e9sus est la r\u00e9ponse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.newcreationtv.org\/fr\/#website\",\"url\":\"https:\/\/www.newcreationtv.org\/fr\/\",\"name\":\"New Creation TV Fran\u00e7ais\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.newcreationtv.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pourquoi J\u00e9sus est la r\u00e9ponse | New Creation TV Fran\u00e7ais","description":"\u00c0 l'homme aveugle de naissance, J\u00e9sus, la lumi\u00e8re du monde, a apport\u00e9 la vue. \u00c0 une foule affam\u00e9e de plus de 5 000 personnes, J\u00e9sus, le pain de vie, a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/","og_locale":"en_US","og_type":"article","og_title":"Pourquoi J\u00e9sus est la r\u00e9ponse | New Creation TV Fran\u00e7ais","og_description":"\u00c0 l'homme aveugle de naissance, J\u00e9sus, la lumi\u00e8re du monde, a apport\u00e9 la vue. \u00c0 une foule affam\u00e9e de plus de 5 000 personnes, J\u00e9sus, le pain de vie, a","og_url":"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/","og_site_name":"New Creation TV Fran\u00e7ais","article_modified_time":"2026-08-28T03:02:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/","url":"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/","name":"Pourquoi J\u00e9sus est la r\u00e9ponse | New Creation TV Fran\u00e7ais","isPartOf":{"@id":"https:\/\/www.newcreationtv.org\/fr\/#website"},"datePublished":"2025-04-14T03:31:28+00:00","dateModified":"2026-08-28T03:02:20+00:00","description":"\u00c0 l'homme aveugle de naissance, J\u00e9sus, la lumi\u00e8re du monde, a apport\u00e9 la vue. \u00c0 une foule affam\u00e9e de plus de 5 000 personnes, J\u00e9sus, le pain de vie, a","breadcrumb":{"@id":"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.newcreationtv.org\/fr\/predication\/pourquoi-jesus-est-la-reponse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.newcreationtv.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Pourquoi J\u00e9sus est la r\u00e9ponse"}]},{"@type":"WebSite","@id":"https:\/\/www.newcreationtv.org\/fr\/#website","url":"https:\/\/www.newcreationtv.org\/fr\/","name":"New Creation TV Fran\u00e7ais","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.newcreationtv.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.newcreationtv.org\/fr\/wp-json\/wp\/v2\/sermon\/10329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newcreationtv.org\/fr\/wp-json\/wp\/v2\/sermon"}],"about":[{"href":"https:\/\/www.newcreationtv.org\/fr\/wp-json\/wp\/v2\/types\/sermon"}],"wp:attachment":[{"href":"https:\/\/www.newcreationtv.org\/fr\/wp-json\/wp\/v2\/media?parent=10329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newcreationtv.org\/fr\/wp-json\/wp\/v2\/categories?post=10329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newcreationtv.org\/fr\/wp-json\/wp\/v2\/tags?post=10329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}